{"id":40,"date":"2015-11-11T13:25:27","date_gmt":"2015-11-11T12:25:27","guid":{"rendered":"https:\/\/www.elflirt.de\/magazin\/?p=40"},"modified":"2026-08-03T10:00:30","modified_gmt":"2026-08-03T08:00:30","slug":"emotionale-abhaengigkeit-in-einer-beziehung","status":"publish","type":"post","link":"https:\/\/www.elflirt.de\/magazin\/emotionale-abhaengigkeit-in-einer-beziehung\/","title":{"rendered":"Emotionale Abh\u00e4ngigkeit in einer Beziehung"},"content":{"rendered":"<p><!-- audio-summary:start --><\/p>\n<h2>Artikel kurz anh\u00f6ren<\/h2>\n<p>Die wichtigsten Punkte kurz und verst\u00e4ndlich zusammengefasst.<\/p>\n<p><audio controls preload=\"none\"><source src=\"https:\/\/www.elflirt.de\/magazin\/wp-content\/uploads\/emotionale-abhaengigkeit-in-einer-beziehung-audio-zusammenfassung.mp3\" type=\"audio\/mpeg\">Dein Browser unterst\u00fctzt das Audio-Element nicht.<\/audio><br \/>\n<!-- audio-summary:end --><\/p>\n<p>Man wird in der Beziehung vom Partner nicht ernst genommen, respektlos behandelt, emotional erpresst. Der Partner verdreht die Fakten, sodass man am Ende selbst an allem Schuld hat. Emotionale Erpressung, Beleidigungen und Schreien sind an der Tagesordnung.<\/p>\n<p>Eigentlich wei\u00df jeder, dass das keine Beziehung mehr ist. Trotzdem stecken nicht wenige Menschen in einer emotionalen Abh\u00e4ngigkeit von ihrem Partner fest, aus der sie schwer wieder herauskommen. Wie kann eine solche Situation entstehen und wie schafft man den Absprung aus einer Beziehung aus emotionaler Abh\u00e4ngigkeit?<\/p>\n<p>Eine emotionale Abh\u00e4ngigkeit l\u00f6sen und eben jene emotionale Abh\u00e4ngigkeit \u00fcberwinden k\u00f6nnen: Es h\u00f6rt sich gar nicht so komplex an und doch ist es ohne Zweifel mit gro\u00dfen Herausforderungen verbunden. Wir wollen uns in den kommenden Abschnitten mit verschiedenen Aspekten der emotionalen Abh\u00e4ngigkeit auseinandersetzen und anschlie\u00dfend nat\u00fcrlich das pr\u00e4sentieren, was so viele Menschen ben\u00f6tigen, die in diese Abh\u00e4ngigkeit zu einem anderen Menschen geraten sind: Einen L\u00f6sungsvorschlag und Wege, die helfen k\u00f6nnen um am Ende wieder zu einem selbstbewussten und sicher auftretenden Menschen zu werden, welcher sich keinesfalls von anderen abh\u00e4ngig machen muss.<\/p>\n<h2>Was ist \u00fcberhaupt emotionale Abh\u00e4ngigkeit?<\/h2>\n<p>Eine Beziehung, in der alles gut l\u00e4uft, kennt keine emotionale Abh\u00e4ngigkeit. &#8222;Es l\u00e4uft gut&#8220; bedeutet, dass sich die Partner gegenseitig geben, was sie von einer Partnerschaft brauchen. In die emotionale Abh\u00e4ngigkeit kann eine Beziehung rutschen, wenn sich das Verh\u00e4ltnis vom gegenseitigen Geben und Nehmen zum einseitigen Konstrukt entwickelt.<\/p>\n<p>Einer der Partner sorgt mit allen Mitteln daf\u00fcr, dass er bekommt, was er braucht und will. Das k\u00f6nnen auch unlautere Mittel wie emotionale Erpressung sein. Der Partner schreit, beleidigt, droht, reagiert mit <!--more-->Liebesentzug &#8211; derartige Beziehungen haben viele schlimme Gesichter.<\/p>\n<p>Die Vernunft sagt: trenn dich! Doch etwas anderes sagt: bleib! Dem emotional abh\u00e4ngigen Partner geht es in dieser Konstellation nicht gut und das wei\u00df er, er redet sich jedoch alles sch\u00f6n und verliert mit der Zeit so sehr das Selbstvertrauen und das Selbstwertgef\u00fchl, dass er denkt, er k\u00f6nne nicht mehr ohne den Partner und habe diese Behandlung vielleicht sogar verdient.<\/p>\n<h2>Wie kann emotionale Abh\u00e4ngigkeit entstehen?<\/h2>\n<p>Emotionale Abh\u00e4ngigkeit setzt eine ganz bestimmte Konstellation zweier Charaktertypen voraus. Es gibt den Partner, der missbraucht, und es gibt den Partner, der den emotionalen Missbrauch zul\u00e4sst. Der missbrauchende Partner hat h\u00e4ufig selbst emotionale Gewalt erfahren und nie gelernt, seine Bed\u00fcrfnisse so zu kommunizieren, dass kein anderer darunter leidet.<\/p>\n<p>Auch er steckt in seiner pers\u00f6nlichen Entwicklung in der Klemme. Der Partner, der den Missbrauch zul\u00e4sst, hat meistens ein geringes Selbstwertgef\u00fchl, was er manchmal selbst nicht wei\u00df. Emotionale Abh\u00e4ngigkeit ist ein schleichender Prozess, der mit weiteren Dem\u00fctigungen in der Beziehungen immer st\u00e4rker wird.<\/p>\n<p>Bis der betroffene Partner merkt, dass er emotional vom anderen abh\u00e4ngig ist und sich daraus l\u00f6sen muss, muss meist sehr viel passieren.<\/p>\n<h2>Die Ursachen der emotionalen Abh\u00e4ngigkeit<\/h2>\n<p>Es geht bei der emotionalen Abh\u00e4ngigkeit zwar durchaus manchmal um Menschen, die mit Pers\u00f6nlichkeitsmerkmalen ausgestattet sind, welche dem Borderline \u00e4hneln, jedoch hei\u00dft dies nicht, dass nicht nahezu jeder unter bestimmten Umst\u00e4nden in die Situation kommen kann, sich in einem solchen Abh\u00e4ngigkeitsverh\u00e4ltnis wiederzufinden.<\/p>\n<p>Einige der Ursachen wollen wir hier darstellen und es wird deutlich werden, dass die Gr\u00fcnde f\u00fcr eine emotionale Abh\u00e4ngigkeit vielschichtig sind. Entt\u00e4uschung in der bestehenden Liebe: Wir leben seit Jahren gl\u00fccklich mit unserem Partner oder unserer Partnerin zusammen und es stellt sich aus dem Nichts heraus, dass er oder sie eine <a href=\"https:\/\/www.elflirt.de\/lexikon\/verliebt-in-affaere.php\">Aff\u00e4re<\/a> hat oder hatte.<\/p>\n<p>In solchen F\u00e4llen f\u00fchlen wir uns naturgem\u00e4\u00df und verst\u00e4ndlicherweise verraten und haben zun\u00e4chst einmal keine L\u00f6sungen, die unsere \u00fcberbordenden Gef\u00fchle kanalisieren w\u00fcrden. Stattdessen neigen einige Menschen dazu, die Schuld bei sich selbst zu suchen und in eine emotionale Abh\u00e4ngigkeit zu geraten.<\/p>\n<p>Wird eben jene Schuldzuweisung vom Partner oder der Partnerin auch noch aufgenommen und im schlimmsten Fall f\u00fcr die eigenen Zwecke ausgenutzt, so kann dies zu einer emotionalen Abh\u00e4ngigkeit f\u00fchren. Schlie\u00dflich hat hier eigentlich der Partner oder die Partnerin den groben Fehler mit der Aff\u00e4re gemacht und trotzdem begeben wir uns durch das beschriebene Handeln in eine Position, in welcher wir v\u00f6llig abh\u00e4ngig von den Handlungen des jeweils anderen sind.<\/p>\n<p>Der <a href=\"https:\/\/www.elflirt.de\/magazin\/narzisten-erkennen-und-mit-ihnen-umgehen\/\">Narzisst<\/a> in der emotionalen Abh\u00e4ngigkeit: Einige Menschen neigen zu narzisstischem Verhalten. Jene Menschen stellen sich in vielen Situationen des Lebens in den Mittelpunkt der Handlung und des Denkens. Dies f\u00fchrt zwar bei einigen zu einem besonders gro\u00dfen Selbstvertrauen, jedoch kann ein solches Denken auch im negativen Falle dazu f\u00fchren, dass man immer mehr Best\u00e4tigung ben\u00f6tigt und somit abh\u00e4ngig von der R\u00fcckmeldung der nah gewordenen Menschen wird.<\/p>\n<p>Ein Narzisst bezieht das Verhalten eines Partners oder einer Partnerin nicht selten auf sich selbst, denn f\u00fcr ihn ist es f\u00f6rmlich undenkbar, dass jenes Verhalten nichts mit ihm selbst zu tun haben k\u00f6nnte. Auch eine emotionale Abh\u00e4ngigkeit vom Ex-Partner ist in solchen F\u00e4llen m\u00f6glich, denn narzisstische Menschen k\u00f6nnen schlicht und einfach in vielen Situationen nicht damit umgehen, dass der oder die andere sie nicht mehr in den Mittelpunkt des eigenen Lebens stellt.<\/p>\n<p>Dies hat mit dem Selbstverst\u00e4ndnis der Menschen zu tun. Emotionale Abh\u00e4ngigkeit und Borderline: Menschen, bei denen das sogenannte Borderline-Syndrom vorliegt, sind in der Regel nur schwerlich dazu in der Lage, eine stabile Beziehung zu f\u00fchren und jene auch konsequent und dauerhaft aufrechtzuerhalten, auch wenn einmal die schwierigen Phasen eintreten, die in jeder l\u00e4nger andauernden Beziehung kommen werden.<\/p>\n<p>Durch die h\u00e4ufig auftretende Impulsivit\u00e4t und das instabile Verhalten dieser Personen kann es dazu kommen, dass sie in eine emotionale Abh\u00e4ngigkeit zum Partner geraten. Dies passiert gerade dann, wenn man in einer Phase, in der sich die eigenen Emotionen wieder beruhigt haben, das Verhalten reflektiert und zu dem Schluss kommt, dass man sich nicht richtig verhalten hat.<\/p>\n<p>Menschen, die unter jenen Symptomen zu leiden haben, sind durchaus in der Lage, das von ihnen gezeigte Verhalten zu reflektieren und die eben beschriebene Reaktion zu zeigen. Im schlechtesten aller anzunehmenden F\u00e4lle f\u00fchrt dies jedoch zu extremen Schuldgef\u00fchlen und der Mensch begibt sich in eine emotionale Abh\u00e4ngigkeit vom Ex-Partner oder aber auch vom jetzigen Partner.<\/p>\n<p>Es handelt sich bei den hier beschriebenen Situationen und F\u00e4llen selbstverst\u00e4ndlich nur um einige wenige M\u00f6glichkeiten, die nur einen Auszug darstellen und nicht das gesamte Spektrum darstellen. Es gibt zahlreiche andere Situationen, in welchen Menschen in eine emotionale Abh\u00e4ngigkeit geraten k\u00f6nnen und neben der Pers\u00f6nlichkeitsstruktur der einzelnen Beteiligten sind es immer auch die derzeit vorherrschenden Lebensumst\u00e4nde, welche eine solche Szenerie beg\u00fcnstigen oder aber verhindern.<\/p>\n<p>Nach einem Schicksalsschlag beispielsweise sind wir in der Regel weniger immun gegen eine drohende emotionale Abh\u00e4ngigkeit, in welcher Situation auch immer sie zustande kommen mag, als in einer Phase in welcher in anderen Lebensbereichen alles gut l\u00e4uft.<\/p>\n<h2>Anzeichen f\u00fcr eine emotionale Abh\u00e4ngigkeit<\/h2>\n<p>Es gibt ganz sicher nicht das eine und alleinige Anzeichen daf\u00fcr, dass ein Mensch sich von einem anderen emotional abh\u00e4ngig gemacht hat und nun in einer schwierigen Situation steckt. Stattdessen sind es verschiedene Aspekte, die Hinweise darauf geben k\u00f6nnen, dass sich eine solche Situation eingeschlichen hat bzw. einzuschleichen droht.<\/p>\n<p>Oft sind es nicht wir selbst, welche die Situation als erstes durchblicken, sondern Menschen aus unserem Umfeld, welche uns schon l\u00e4nger kennen und nun eine \u00c4nderung in unseren Verhaltensweisen feststellen. Es sind dennoch einige typische Anzeichen, die uns ins Nachdenken bringen sollten und f\u00fcr eine emotionale Abh\u00e4ngigkeit stehen k\u00f6nnten: 1.<\/p>\n<p>Abkopplung vom sonstigen Umfeld und ggf. sogar von der Familie: Emotional abh\u00e4ngige Menschen neigen dazu, nur noch den einen Menschen um den sich ihr Leben nun dreht, in den Mittelpunkt ihres Seins zu stellen. Sie tauchen f\u00fcr ihren Freundeskreis und in extremen F\u00e4llen gar f\u00fcr den Rest ihrer Familie v\u00f6llig unter.<\/p>\n<p>Auf Kritik an jenem Verhalten reagieren sie nicht selten barsch und weisen selbige rigoros zur\u00fcck. 2. Zur\u00fcckstellen eigener Interessen: Hat man im Vorfeld der nun eingetretenen Situation noch Hobbys gepflegt und ist den eigenen Interessen nachgegangen, so steht nun lediglich die Beziehung mit dem Partner oder der Partnerin bzw. mit dem Ex-Partner oder der Ex-Partnerin des eigenen Seins und aller Handlungen.<\/p>\n<p>Wenn das Interesse an eigentlich lieb gewonnenen und lange gepflegten Hobbys in schwierigen Beziehungssituationen schwindet und sich die Gedanken lediglich um selbige Situation drehen, so kann dies ein Anzeichen f\u00fcr eine vorhandene oder drohende emotionale Abh\u00e4ngigkeit sein.<\/p>\n<p>3. Fehler werden grunds\u00e4tzlich in der eigenen Person gesucht: Bestehen in einer Beziehung in der der eine Partner emotional vom anderen abh\u00e4ngig ist Streitigkeiten bzw. Konflikte, so sucht derjenige Part alle Fehler bei sich selbst und ist gar bem\u00fcht, das eigene Verhalten oder aber die eigene Pers\u00f6nlichkeitsstruktur so weit umzustellen, dass man den Vorstellungen des anderen Beziehungsteils komplett entspricht.<\/p>\n<p>Vorsicht: Es spricht nichts dagegen, dem Partner oder der Partnerin auch in schwierigen Fragen einmal entgegenzukommen und uns anzupassen. Ein gewisses Ma\u00df an Bereitschaft dazu ist bei beiden Teilen der Beziehung ganz sicher sogar eine Voraussetzung f\u00fcr ein gelungenes Zusammenleben.<\/p>\n<p>Geben wir jedoch wichtige Prinzipien aus und erkennen uns selbst im Verhalten und Auftreten nicht mehr wieder, so geht die Anpassung definitiv zu weit und wir drohen in eine emotionale Abh\u00e4ngigkeit zu geraten oder sind dies schon.<\/p>\n<h2>Selbsttest: Befinde ich mich in einer emotionalen Abh\u00e4ngigkeit?<\/h2>\n<p>Wie bereits erw\u00e4hnt sind es oft Menschen aus dem Umfeld, die zuerst erkennen, dass wir uns in eine emotionale Abh\u00e4ngigkeit begeben haben und nun nicht mehr f\u00fcr uns selbst, sondern nur noch f\u00fcr die Aufrechterhaltung einer Beziehung handeln.<\/p>\n<p>Um dies selbst zu erkennen, lohnt es sich einige Fragen ehrlich und offen f\u00fcr sich selbst zu beantworten und sich anschlie\u00dfend kritisch mit dem eigenen Verhalten zu besch\u00e4ftigen. Je fr\u00fcher wir das Abrutschen in eine emotionale Abh\u00e4ngigkeit erkennen, umso leichter f\u00e4llt uns der Ausweg noch.<\/p>\n<p>Hier einige relevante Fragen: <\/p>\n<ol>\n<li>Habe ich meinen Freundinnen und Freunden in der letzten Zeit oft abgesagt, um bei der Person zu sein, auch wenn wir keine dringliche Verabredung hatten?<\/li>\n<li>Verfolge ich meine Hobbys und Interessen in der letzten Zeit weniger und kann dies in der Tatsache begr\u00fcndet sein, dass es sich bei ihnen nicht gleichzeitig um seine oder ihre Interessen handelt?<\/li>\n<li>Besch\u00e4ftige ich mich mit der eigenen Weiterentwicklung, ob im beruflichen oder pers\u00f6nlichen Kontext oder stelle ich mich selbst komplett f\u00fcr die Beziehung zur\u00fcck?<\/li>\n<li>Habe ich f\u00fcr mich wichtige Prinzipien im Laufe der Beziehung in seinem oder ihrem Sinne aufgegeben?<\/li>\n<\/ol>\n<h2>Wie l\u00f6st man sich aus emotionaler Abh\u00e4ngigkeit?<\/h2>\n<p>&#8222;Habe ich diese schlechte Behandlung verdient?&#8220; &#8222;Warum bin ich ein so schlechter Partner?&#8220; &#8222;Er\/Sie kann mich nur so behandeln, weil ich Schuld daran bin!&#8220; Solche Gedanken sind typisch f\u00fcr emotionale Abh\u00e4ngigkeit. Der missbrauchende Partner treibt den anderen so weit, dass er selbst glaubt, die Verantwortung f\u00fcr die schlecht laufende Beziehung l\u00e4ge an ihm.<\/p>\n<p>Meistens hat sich diese \u00dcberzeugung so gefestigt, dass der Betroffene Hilfe braucht, um sich aus der Beziehung zu l\u00f6sen. Die Schwierigkeit dabei ist, dass man einen Menschen nicht dazu zwingen kann, <a href=\"https:\/\/www.elflirt.de\/magazin\/beziehung-beenden\/\">eine Beziehung zu beenden<\/a>, selbst wenn man als Au\u00dfenstehender sieht, dass er emotional misshandelt wird.<\/p>\n<p>Der erste Impuls muss vom betroffenen Partner selbst kommen. Vielen hilft bereits ein Selbsttest, der die Beziehung kritisch unter die Lupe nimmt und ihnen die Augen daf\u00fcr \u00f6ffnet, dass das nicht normal ist, was sie erleben.<\/p>\n<p>Gerade bei l\u00e4nger andauernder emotionaler Abh\u00e4ngigkeit reicht leider nur noch ein Paukenschlag oder ein schlimmes Ereignis, um dem Betroffenen die Augen daf\u00fcr zu \u00f6ffnen, dass es so nicht weitergehen kann. Wichtig ist nur, dass der Entschluss getroffen wird, die Beziehung zu beenden.<\/p>\n<p>Ist diese \u00dcberzeugung gekommen, gibt es eine Reihe von Hilfen von Selbsthilfekreisen bis hin zu professioneller psychologischer Betreuung f\u00fcr emotional Abh\u00e4ngige.<\/p>\n<h2>Mit unseren Tipps die emotionale Abh\u00e4ngigkeit \u00fcberwinden<\/h2>\n<p>Zum Abschluss unserer Auseinandersetzung haben wir 5 Tipps zusammengestellt, die dabei helfen sollen, eine emotionale Abh\u00e4ngigkeit l\u00f6sen zu k\u00f6nnen: 1. Gespr\u00e4che mit Freundinnen und Freunden: Wir alle haben Vertrauenspersonen im eigenen Leben, die uns besser kennen als andere Menschen und die in der Lage sind, uns auch in einer hier vorgestellten Situation zu helfen.<\/p>\n<p>Nun ist die Zeit, sich einfach einmal auszusprechen und Trost oder Ablenkung zu finden. 2. Ablenkung durch die Wiederaufnahme von Hobbys: Unsere Hobbys haben es schon einmal geschafft, ein hohes Ma\u00df an Aufmerksamkeit zu binden und sie w\u00e4ren nicht unsere Hobbys geworden, wenn sie nicht in der Lage w\u00e4ren uns gl\u00fccklich zu machen.<\/p>\n<p>3. Schriftliche Verarbeitung: Es gibt weiterhin viele Menschen, denen es hilft, die eigenen Gef\u00fchle und Gedanken zu verchristlichen. Dabei ist es auch einfacher m\u00f6glich, sich im Anschluss reflektiert und kritisch mit der eigenen Gedankenwelt zu besch\u00e4ftigen.<\/p>\n<p>4. Das Ziel deutlich machen: Nur wenn es das klare Ziel ist, die emotionale Abh\u00e4ngigkeit \u00fcberwinden zu wollen, so besteht durch die oben beschriebenen Handlungen auch die M\u00f6glichkeit dazu. 5. Emotionale Abh\u00e4ngigkeit Therapie: Die drei Begriffe ,,Emotionale Abh\u00e4ngigkeit Therapie&#8220; sind keineswegs ein Grund zur Scham, sondern zeigen ganz klar die pers\u00f6nliche St\u00e4rke, dass man sich seiner Probleme bewusst ist und gewillt ist, in Zukunft wieder gl\u00fccklich und selbstsicher durchs Leben zu gehen.<\/p>\n<hr \/>\n<p> <em>Bildquelle: fotolia #91984726 @yanlev<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Artikel kurz anh\u00f6ren Die wichtigsten Punkte kurz und verst\u00e4ndlich zusammengefasst. Dein Browser unterst\u00fctzt das Audio-Element nicht. Man wird in der<\/p>\n","protected":false},"author":4,"featured_media":46,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-40","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-psychologie","comments-off"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Was ist \u00fcberhaupt emotionale Abh\u00e4ngigkeit? Und wie l\u00f6st man sich wenn man diese f\u00fcr sich erkannt hat? Hier zu lesen.\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"Christian M. Haas\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.elflirt.de\/magazin\/emotionale-abhaengigkeit-in-einer-beziehung\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.elflirt.de\\\/magazin\\\/emotionale-abhaengigkeit-in-einer-beziehung\\\/#article\",\"name\":\"Emotionale Abh\\u00e4ngigkeit | elFlirt.de\",\"headline\":\"Emotionale Abh\\u00e4ngigkeit in einer Beziehung\",\"author\":{\"@id\":\"https:\\\/\\\/www.elflirt.de\\\/magazin\\\/author\\\/christian-m-haas\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.elflirt.de\\\/magazin\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.elflirt.de\\\/magazin\\\/wp-content\\\/uploads\\\/emotionale-abhaengigkeit.jpg\",\"width\":424,\"height\":283,\"caption\":\"Emotionale Abh\\u00e4ngigkeit\"},\"datePublished\":\"2015-11-11T13:25:27+01:00\",\"dateModified\":\"2026-08-03T10:00:30+02:00\",\"inLanguage\":\"de-DE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.elflirt.de\\\/magazin\\\/emotionale-abhaengigkeit-in-einer-beziehung\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.elflirt.de\\\/magazin\\\/emotionale-abhaengigkeit-in-einer-beziehung\\\/#webpage\"},\"articleSection\":\"Psychologie\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.elflirt.de\\\/magazin\\\/emotionale-abhaengigkeit-in-einer-beziehung\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elflirt.de\\\/magazin#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.elflirt.de\\\/magazin\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elflirt.de\\\/magazin\\\/thema\\\/psychologie\\\/#listItem\",\"name\":\"Psychologie\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elflirt.de\\\/magazin\\\/thema\\\/psychologie\\\/#listItem\",\"position\":2,\"name\":\"Psychologie\",\"item\":\"https:\\\/\\\/www.elflirt.de\\\/magazin\\\/thema\\\/psychologie\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elflirt.de\\\/magazin\\\/emotionale-abhaengigkeit-in-einer-beziehung\\\/#listItem\",\"name\":\"Emotionale Abh\\u00e4ngigkeit in einer Beziehung\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elflirt.de\\\/magazin#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elflirt.de\\\/magazin\\\/emotionale-abhaengigkeit-in-einer-beziehung\\\/#listItem\",\"position\":3,\"name\":\"Emotionale Abh\\u00e4ngigkeit in einer Beziehung\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elflirt.de\\\/magazin\\\/thema\\\/psychologie\\\/#listItem\",\"name\":\"Psychologie\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.elflirt.de\\\/magazin\\\/#organization\",\"name\":\"elFlirt\",\"url\":\"https:\\\/\\\/www.elflirt.de\\\/magazin\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.elflirt.de\\\/magazin\\\/wp-content\\\/uploads\\\/elflirt-logo.png\",\"@id\":\"https:\\\/\\\/www.elflirt.de\\\/magazin\\\/emotionale-abhaengigkeit-in-einer-beziehung\\\/#organizationLogo\",\"width\":188,\"height\":100,\"caption\":\"elFlirt Logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.elflirt.de\\\/magazin\\\/emotionale-abhaengigkeit-in-einer-beziehung\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.elflirt.de\\\/magazin\\\/author\\\/christian-m-haas\\\/#author\",\"url\":\"https:\\\/\\\/www.elflirt.de\\\/magazin\\\/author\\\/christian-m-haas\\\/\",\"name\":\"Christian M. Haas\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.elflirt.de\\\/magazin\\\/emotionale-abhaengigkeit-in-einer-beziehung\\\/#authorImage\",\"url\":\"https:\\\/\\\/www.elflirt.de\\\/magazin\\\/wp-content\\\/uploads\\\/Christian-M-Haas-Middle.png\",\"width\":900,\"height\":1110},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/christian-m-haas-457323379\",\"https:\\\/\\\/datingnischen.de\\\/christian\\\/\"],\"jobTitle\":\"Datingexperte\",\"knowsLanguage\":[\"Deutsch\",\"Englisch\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.elflirt.de\\\/magazin\\\/emotionale-abhaengigkeit-in-einer-beziehung\\\/#webpage\",\"url\":\"https:\\\/\\\/www.elflirt.de\\\/magazin\\\/emotionale-abhaengigkeit-in-einer-beziehung\\\/\",\"name\":\"Emotionale Abh\\u00e4ngigkeit | elFlirt.de\",\"description\":\"Was ist \\u00fcberhaupt emotionale Abh\\u00e4ngigkeit? Und wie l\\u00f6st man sich wenn man diese f\\u00fcr sich erkannt hat? Hier zu lesen.\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.elflirt.de\\\/magazin\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.elflirt.de\\\/magazin\\\/emotionale-abhaengigkeit-in-einer-beziehung\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.elflirt.de\\\/magazin\\\/author\\\/christian-m-haas\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.elflirt.de\\\/magazin\\\/author\\\/christian-m-haas\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.elflirt.de\\\/magazin\\\/wp-content\\\/uploads\\\/emotionale-abhaengigkeit.jpg\",\"@id\":\"https:\\\/\\\/www.elflirt.de\\\/magazin\\\/emotionale-abhaengigkeit-in-einer-beziehung\\\/#mainImage\",\"width\":424,\"height\":283,\"caption\":\"Emotionale Abh\\u00e4ngigkeit\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.elflirt.de\\\/magazin\\\/emotionale-abhaengigkeit-in-einer-beziehung\\\/#mainImage\"},\"datePublished\":\"2015-11-11T13:25:27+01:00\",\"dateModified\":\"2026-08-03T10:00:30+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.elflirt.de\\\/magazin\\\/#website\",\"url\":\"https:\\\/\\\/www.elflirt.de\\\/magazin\\\/\",\"name\":\"elFlirt - Magazin\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.elflirt.de\\\/magazin\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Emotionale Abh\u00e4ngigkeit | elFlirt.de<\/title>\n\n","aioseo_head_json":{"title":"Emotionale Abh\u00e4ngigkeit | elFlirt.de","description":"Was ist \u00fcberhaupt emotionale Abh\u00e4ngigkeit? Und wie l\u00f6st man sich wenn man diese f\u00fcr sich erkannt hat? Hier zu lesen.","canonical_url":"https:\/\/www.elflirt.de\/magazin\/emotionale-abhaengigkeit-in-einer-beziehung\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.elflirt.de\/magazin\/emotionale-abhaengigkeit-in-einer-beziehung\/#article","name":"Emotionale Abh\u00e4ngigkeit | elFlirt.de","headline":"Emotionale Abh\u00e4ngigkeit in einer Beziehung","author":{"@id":"https:\/\/www.elflirt.de\/magazin\/author\/christian-m-haas\/#author"},"publisher":{"@id":"https:\/\/www.elflirt.de\/magazin\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.elflirt.de\/magazin\/wp-content\/uploads\/emotionale-abhaengigkeit.jpg","width":424,"height":283,"caption":"Emotionale Abh\u00e4ngigkeit"},"datePublished":"2015-11-11T13:25:27+01:00","dateModified":"2026-08-03T10:00:30+02:00","inLanguage":"de-DE","mainEntityOfPage":{"@id":"https:\/\/www.elflirt.de\/magazin\/emotionale-abhaengigkeit-in-einer-beziehung\/#webpage"},"isPartOf":{"@id":"https:\/\/www.elflirt.de\/magazin\/emotionale-abhaengigkeit-in-einer-beziehung\/#webpage"},"articleSection":"Psychologie"},{"@type":"BreadcrumbList","@id":"https:\/\/www.elflirt.de\/magazin\/emotionale-abhaengigkeit-in-einer-beziehung\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.elflirt.de\/magazin#listItem","position":1,"name":"Home","item":"https:\/\/www.elflirt.de\/magazin","nextItem":{"@type":"ListItem","@id":"https:\/\/www.elflirt.de\/magazin\/thema\/psychologie\/#listItem","name":"Psychologie"}},{"@type":"ListItem","@id":"https:\/\/www.elflirt.de\/magazin\/thema\/psychologie\/#listItem","position":2,"name":"Psychologie","item":"https:\/\/www.elflirt.de\/magazin\/thema\/psychologie\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.elflirt.de\/magazin\/emotionale-abhaengigkeit-in-einer-beziehung\/#listItem","name":"Emotionale Abh\u00e4ngigkeit in einer Beziehung"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.elflirt.de\/magazin#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.elflirt.de\/magazin\/emotionale-abhaengigkeit-in-einer-beziehung\/#listItem","position":3,"name":"Emotionale Abh\u00e4ngigkeit in einer Beziehung","previousItem":{"@type":"ListItem","@id":"https:\/\/www.elflirt.de\/magazin\/thema\/psychologie\/#listItem","name":"Psychologie"}}]},{"@type":"Organization","@id":"https:\/\/www.elflirt.de\/magazin\/#organization","name":"elFlirt","url":"https:\/\/www.elflirt.de\/magazin\/","logo":{"@type":"ImageObject","url":"https:\/\/www.elflirt.de\/magazin\/wp-content\/uploads\/elflirt-logo.png","@id":"https:\/\/www.elflirt.de\/magazin\/emotionale-abhaengigkeit-in-einer-beziehung\/#organizationLogo","width":188,"height":100,"caption":"elFlirt Logo"},"image":{"@id":"https:\/\/www.elflirt.de\/magazin\/emotionale-abhaengigkeit-in-einer-beziehung\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.elflirt.de\/magazin\/author\/christian-m-haas\/#author","url":"https:\/\/www.elflirt.de\/magazin\/author\/christian-m-haas\/","name":"Christian M. Haas","image":{"@type":"ImageObject","@id":"https:\/\/www.elflirt.de\/magazin\/emotionale-abhaengigkeit-in-einer-beziehung\/#authorImage","url":"https:\/\/www.elflirt.de\/magazin\/wp-content\/uploads\/Christian-M-Haas-Middle.png","width":900,"height":1110},"sameAs":["https:\/\/www.linkedin.com\/in\/christian-m-haas-457323379","https:\/\/datingnischen.de\/christian\/"],"jobTitle":"Datingexperte","knowsLanguage":["Deutsch","Englisch"]},{"@type":"WebPage","@id":"https:\/\/www.elflirt.de\/magazin\/emotionale-abhaengigkeit-in-einer-beziehung\/#webpage","url":"https:\/\/www.elflirt.de\/magazin\/emotionale-abhaengigkeit-in-einer-beziehung\/","name":"Emotionale Abh\u00e4ngigkeit | elFlirt.de","description":"Was ist \u00fcberhaupt emotionale Abh\u00e4ngigkeit? Und wie l\u00f6st man sich wenn man diese f\u00fcr sich erkannt hat? Hier zu lesen.","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/www.elflirt.de\/magazin\/#website"},"breadcrumb":{"@id":"https:\/\/www.elflirt.de\/magazin\/emotionale-abhaengigkeit-in-einer-beziehung\/#breadcrumblist"},"author":{"@id":"https:\/\/www.elflirt.de\/magazin\/author\/christian-m-haas\/#author"},"creator":{"@id":"https:\/\/www.elflirt.de\/magazin\/author\/christian-m-haas\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.elflirt.de\/magazin\/wp-content\/uploads\/emotionale-abhaengigkeit.jpg","@id":"https:\/\/www.elflirt.de\/magazin\/emotionale-abhaengigkeit-in-einer-beziehung\/#mainImage","width":424,"height":283,"caption":"Emotionale Abh\u00e4ngigkeit"},"primaryImageOfPage":{"@id":"https:\/\/www.elflirt.de\/magazin\/emotionale-abhaengigkeit-in-einer-beziehung\/#mainImage"},"datePublished":"2015-11-11T13:25:27+01:00","dateModified":"2026-08-03T10:00:30+02:00"},{"@type":"WebSite","@id":"https:\/\/www.elflirt.de\/magazin\/#website","url":"https:\/\/www.elflirt.de\/magazin\/","name":"elFlirt - Magazin","inLanguage":"de-DE","publisher":{"@id":"https:\/\/www.elflirt.de\/magazin\/#organization"}}]}},"aioseo_meta_data":{"post_id":"40","title":"Emotionale Abh\u00e4ngigkeit | elFlirt.de","description":"Was ist \u00fcberhaupt emotionale Abh\u00e4ngigkeit? Und wie l\u00f6st man sich wenn man diese f\u00fcr sich erkannt hat? Hier zu lesen.","keywords":[],"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"none","schema_type_options":"{\"webPage\":{\"webPageType\":\"WebPage\"},\"article\":{\"articleType\":\"BlogPosting\"},\"book\":[],\"course\":[],\"event\":[],\"jobPosting\":[],\"music\":[],\"person\":[],\"product\":[],\"recipe\":[],\"restaurant\":[],\"service\":[],\"software\":[],\"video\":[]}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":{"businessInfo":{"name":"","urls":{"website":"","aboutPage":"","contactPage":""},"address":{"line1":"","line2":"","zip":"","city":"","state":"","country":""},"contact":{"email":"","phone":"","fax":""},"ids":{"vatID":"","taxID":"","chamberID":""},"payment":{"priceIndication":"","currenciesAccepted":"","methodsAccepted":""},"areaServed":""},"openingHours":{"show":false,"closedLabel":"","open24h":false,"open24hLabel":"","open247":false,"use24hFormat":false,"twoSets":false,"timezone":"","hours":[]}},"seo_analyzer_scan_date":"2026-08-03 14:01:24","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 04:00:39","updated":"2026-08-03 14:01:26","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"_links":{"self":[{"href":"https:\/\/www.elflirt.de\/magazin\/wp-json\/wp\/v2\/posts\/40","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elflirt.de\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elflirt.de\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elflirt.de\/magazin\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elflirt.de\/magazin\/wp-json\/wp\/v2\/comments?post=40"}],"version-history":[{"count":7,"href":"https:\/\/www.elflirt.de\/magazin\/wp-json\/wp\/v2\/posts\/40\/revisions"}],"predecessor-version":[{"id":1661,"href":"https:\/\/www.elflirt.de\/magazin\/wp-json\/wp\/v2\/posts\/40\/revisions\/1661"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elflirt.de\/magazin\/wp-json\/wp\/v2\/media\/46"}],"wp:attachment":[{"href":"https:\/\/www.elflirt.de\/magazin\/wp-json\/wp\/v2\/media?parent=40"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elflirt.de\/magazin\/wp-json\/wp\/v2\/categories?post=40"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elflirt.de\/magazin\/wp-json\/wp\/v2\/tags?post=40"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}